{"id":4468,"date":"2020-06-15T17:35:26","date_gmt":"2020-06-15T14:35:26","guid":{"rendered":"https:\/\/mpatsios.digital-media.gr\/etiketes-etiketografon\/"},"modified":"2020-09-15T10:50:29","modified_gmt":"2020-09-15T07:50:29","slug":"etiketes-etiketografon","status":"publish","type":"page","link":"https:\/\/batsios.gr\/en\/etiketes-etiketografon\/","title":{"rendered":"Labels for Labelers"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;70&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"ult-new-ib ult-ib-effect-style6  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"0.5\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:0.5;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/a4.jpg\"   \/><div id=\"interactive-banner-wrap-7034\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7034 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Labels in A4 Sheets<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/etiketes-se-fylla-a4\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script><div class=\"ult-new-ib ult-ib-effect-style6  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"0.5\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:0.5;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/Synthetikes_Etiketes1.jpg\"   \/><div id=\"interactive-banner-wrap-6442\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-6442 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Synthetic Labels<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/synthetikes-etiketes\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"ult-new-ib ult-ib-effect-style6  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"0.5\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:0.5;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/fillarakia.jpg\"   \/><div id=\"interactive-banner-wrap-7556\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7556 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Labels in Sheets 10x15cm<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/etiketes-se-fylla-10x15cm\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script><div class=\"ult-new-ib ult-ib-effect-style6  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"0.5\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:0.5;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/Etiketes_gia_inkjet1.jpg\"   \/><div id=\"interactive-banner-wrap-2151\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-2151 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Labels for inkjet printers<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/etiketes-gia-inkjet-printers\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"ult-new-ib ult-ib-effect-style14  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"1\" data-hover-opacity=\"0.5\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/Etiketes_Etiketografon1.jpg\"   \/><div id=\"interactive-banner-wrap-3225\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-3225 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Labels for Labelers<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/etiketes-etiketografon\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"ult-new-ib ult-ib-effect-style6  ult-ib-resp  \" data-min-width=\"768\" data-max-width=\"900\" style=\"background:#000000;\" data-opacity=\"0.5\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:0.5;\" alt=\"null\" src=\"https:\/\/batsios.gr\/wp-content\/uploads\/2020\/07\/Etiketes_biomixanikis_xrisis1.jpg\"   \/><div id=\"interactive-banner-wrap-6348\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-6348 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Industrial Labels<\/h2><\/div><a class=\"ult-new-ib-link\" href=\"\/etiketes-viomichanikis-chrisis\/\"  ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]Labels for labelers are available in dimensions (mm):<\/p>\n<ul>\n<li>21&#215;12<\/li>\n<li>22&#215;12<\/li>\n<li>26&#215;12<\/li>\n<li>26&#215;16<\/li>\n<li>32&#215;19<\/li>\n<\/ul>\n<p>The labels are available with permanent adhesive (suitable for freezing conditions) as well as in fluorescent material.<\/p>\n<p>There is a stock of frequently used standard labels.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;50&#8243; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;3581&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221; img_link=&#8221;\/etiketes-syskeyasias-trofimon-argie\/&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;70&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":16,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4468","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/pages\/4468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/comments?post=4468"}],"version-history":[{"count":6,"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/pages\/4468\/revisions"}],"predecessor-version":[{"id":4726,"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/pages\/4468\/revisions\/4726"}],"wp:attachment":[{"href":"https:\/\/batsios.gr\/en\/wp-json\/wp\/v2\/media?parent=4468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}